{"id":54192,"date":"2023-11-12T12:09:42","date_gmt":"2023-11-12T12:09:42","guid":{"rendered":"https:\/\/goldbergloren.com\/california-workers-compensation-attorneys\/"},"modified":"2025-07-30T19:14:04","modified_gmt":"2025-07-30T19:14:04","slug":"california-abogados-indemnizacion-accidente-laboral","status":"publish","type":"page","link":"https:\/\/goldbergloren.com\/es\/california-abogados-indemnizacion-accidente-laboral\/","title":{"rendered":"Abogados de Indemnizaci\u00f3n por Accidente Laboral en California"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"54192\" class=\"elementor elementor-54192 elementor-46123\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5e5c41d elementor-section-height-min-height elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5e5c41d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d1573f\" data-id=\"1d1573f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c84c9e elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7c84c9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Abogados con experiencia en Indemnizaci\u00f3n Laboral de California en una sola llamada<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9504a0d elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9504a0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Abogados de indemnizaci\u00f3n por accidente laboral en California<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b37d10 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6b37d10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Somos uno de los mejores bufetes de abogados de compensaci\u00f3n laboral de California.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18520fd elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"18520fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/05\/gl-m-1.gif\" class=\"attachment-large size-large wp-image-37633\" alt=\"James Loren y George Goldberg\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6514689 elementor-mobile-align-center elementor-align-left elementor-tablet-align-center elementor-widget elementor-widget-bdt-advanced-button\" data-id=\"6514689\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-button.default\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-button-wrapper\">\n\t\t\t<a href=\"\/contact\/#form\" class=\"bdt-ep-button bdt-ep-button-effect-d bdt-ep-button-size-md\">\n\t\t\t\t\t\t<div class=\"bdt-ep-button-content-wrapper bdt-flex bdt-flex-middle bdt-flex-center\" data-text=\"Obtenga una consulta gratuita\">\n\t\t\t\t\t\t\t<div class=\"bdt-ep-button-icon bdt-flex-center bdt-flex-align-right\">\n\t\t\t\t\t<div class=\"bdt-ep-button-icon-inner\">\n\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa-fw fas fa-long-arrow-alt-right\"><\/i>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"bdt-ep-button-text\">\n\n\t\t\t\t<span class=\"avdbtn-text\">\n\t\t\t\t\tObtenga una consulta gratuita\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e1b2ea8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1b2ea8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b59604\" data-id=\"5b59604\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d05127 elementor-widget elementor-widget-pp-breadcrumbs\" data-id=\"5d05127\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;breadcrumbs_type&quot;:&quot;rankmath&quot;}\" data-widget_type=\"pp-breadcrumbs.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-breadcrumbs pp-breadcrumbs-rankmath\">\n\t\t\t\t\t<nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Home<\/span><\/p><\/nav>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-16f55d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16f55d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ba8fe69 content\" data-id=\"ba8fe69\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a6eb9e1 elementor-widget elementor-widget-menu-anchor\" data-id=\"a6eb9e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-1\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa81291 elementor-widget elementor-widget-heading\" data-id=\"fa81291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Indemnizaci\u00f3n Por Accidente Laboral es Un Seguro Sin Culpa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa08a83 elementor-widget elementor-widget-text-editor\" data-id=\"fa08a83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La indemnizaci\u00f3n por accidente laboral es un sistema de seguro sin culpa que proporciona prestaciones econ\u00f3micas a los trabajadores que sufren lesiones o enfermedades laborales. Este sistema garantiza que el trabajador lesionado pueda recibir atenci\u00f3n m\u00e9dica y salarios perdidos, independientemente de qui\u00e9n sea el culpable de la lesi\u00f3n.<\/p><p>\u00a0En California, tanto empleadores como trabajadores contribuyen a este fondo com\u00fan de seguros sin culpa. Por tanto, cuando un trabajador sufre una lesi\u00f3n en el lugar de trabajo, tiene derecho a prestaciones de indemnizaci\u00f3n por accidente laboral, independientemente de qui\u00e9n sea el culpable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d41193 elementor-widget elementor-widget-image\" data-id=\"6d41193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"940\" height=\"629\" src=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-injury-form.jpg\" class=\"attachment-full size-full wp-image-46552\" alt=\"La Indemnizaci\u00f3n Por Accidente Laboral es Un Seguro Sin Culpa\" srcset=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-injury-form.jpg 940w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-injury-form-300x201.jpg 300w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-injury-form-768x514.jpg 768w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdfe6bb elementor-widget elementor-widget-menu-anchor\" data-id=\"bdfe6bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-2\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7b09a2 elementor-widget elementor-widget-heading\" data-id=\"e7b09a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Como Pueden Suceder Las Lesiones Laborales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131d343 elementor-widget elementor-widget-text-editor\" data-id=\"131d343\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p id=\"54eb9da0-05f1-4b6b-a368-4c80e70866ec\" class=\"quill-block\">Las lesiones laborales pueden suceder por diversos motivos, desde condiciones de trabajo inseguras hasta negligencia de los empleados. [1]<\/p><p>Las causas de las lesiones relacionadas con el trabajo pueden desglosarse en uno de varios grupos, entre los que se incluyen:<\/p><ol><li>Exposici\u00f3n a sustancias o entornos nocivos<\/li><li>Sobreesfuerzo y reacci\u00f3n corporal<\/li><li>Resbalones, tropiezos y ca\u00eddas<\/li><li>Contacto con objetos y equipos<\/li><li>Incidentes de transporte<\/li><li>Violencia y otras lesiones causadas por personas o animales<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b751413 elementor-widget elementor-widget-menu-anchor\" data-id=\"b751413\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-3\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aea8edf elementor-widget elementor-widget-heading\" data-id=\"aea8edf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leyes de Indemnizaci\u00f3n Laboral de California<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51eba65 elementor-widget elementor-widget-text-editor\" data-id=\"51eba65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Si te lesionas en el trabajo, puedes tener derecho a recibir prestaciones a trav\u00e9s del sistema de indemnizaci\u00f3n para los trabajadores de California. Este sistema est\u00e1 regulado por la Divisi\u00f3n de Indemnizaci\u00f3n por Accidentes de Trabajo (DWC). En virtud del DWC, los trabajadores lesionados tienen derecho a asistencia m\u00e9dica y al reembolso de los salarios perdidos relacionados con su lesi\u00f3n.<\/p><p>En California, los empleadores deben proporcionar un seguro de indemnizaci\u00f3n a sus empleados o pueden enfrentarse a sanciones. El DWC tambi\u00e9n establece directrices sobre la cuant\u00eda de la indemnizaci\u00f3n a la que tiene derecho un trabajador lesionado, incluidas las facturas m\u00e9dicas, los salarios perdidos y otras prestaciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b062ee7 elementor-widget elementor-widget-menu-anchor\" data-id=\"b062ee7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-4\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7922293 elementor-widget elementor-widget-heading\" data-id=\"7922293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 Debes Hacer Si Te Lesionas en El Trabajo?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65f9c06 elementor-widget elementor-widget-text-editor\" data-id=\"65f9c06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Si sufres una lesi\u00f3n en el trabajo, es importante que tomes las medidas necesarias para garantizar la protecci\u00f3n de tus derechos. El primer paso es informar inmediatamente de la lesi\u00f3n a tu empleador.<\/p><p>Rellena el <a href=\"https:\/\/www.dir.ca.gov\/dwc\/dwcform1.pdf\" target=\"_blank\" rel=\"noopener\">formulario de solicitud de indemnizaci\u00f3n por accidente laboral (DWC 1)<\/a><\/p><p>Busca atenci\u00f3n m\u00e9dica para tu lesi\u00f3n. Esto garantizar\u00e1 que recibas la atenci\u00f3n m\u00e9dica necesaria para tratar tu lesi\u00f3n y ayudarte a recuperarte lo antes posible. Adem\u00e1s, es importante llevar un registro detallado de todas las facturas m\u00e9dicas y salarios perdidos relacionados con tu lesi\u00f3n. Estos registros pueden ser muy valiosos a la hora de solicitar prestaciones por accidentes laborales.<\/p><p>Si tienes dificultades para desenvolverte en el sistema de compesaci\u00f3n para los trabajadores o para obtener las prestaciones a las que crees tener derecho, es importante que te pongas en contacto con un abogado experto en compensaci\u00f3n de los trabajadores de California.<\/p><p>\u00a0Nuestros abogados especializados en indemnizaci\u00f3n por accidente laboral pueden ayudarte a garantizar la protecci\u00f3n de tus derechos y a que recibas la totalidad de las prestaciones que mereces.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1cbaab elementor-widget elementor-widget-menu-anchor\" data-id=\"a1cbaab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-5\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3292faf elementor-widget elementor-widget-heading\" data-id=\"3292faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les Son Mis Derechos Tras Sufrir Una Lesi\u00f3n Laboral en California?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc5e545 elementor-widget elementor-widget-text-editor\" data-id=\"dc5e545\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cuando te lesionas en el trabajo, tienes ciertos derechos que deben ser protegidos. Estos incluyen tratamiento m\u00e9dico y prestaciones, un lugar de trabajo seguro y protecci\u00f3n frente a represalias por presentar un reclamo.<\/p><p>Tu empleador debe proporcionarte todo el tratamiento m\u00e9dico necesario relacionado con tu lesi\u00f3n. Esto incluye visitas al m\u00e9dico, estancias en el hospital, fisioterapia y medicamentos.<\/p><p>Tu empleador tambi\u00e9n es responsable de proporcionar un lugar de trabajo seguro. Esto significa que deben seguir todos los protocolos y normas de seguridad para evitar lesiones en el lugar de trabajo.<\/p><p>Por \u00faltimo, tienes derecho a no sufrir represalias por presentar un reclamo de indemnizaci\u00f3n por accidente laboral. Tu empleador no puede castigarte ni discriminarte por presentar una reclamaci\u00f3n leg\u00edtima o intentar recibir prestaciones.\u00a0<\/p><p>Si crees que tu empleador est\u00e1 tomando represalias contra ti, ponte en contacto inmediatamente con un abogado experto en indemnizaci\u00f3n por accidente laboral.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-940f8e7\" data-id=\"940f8e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-330c5f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"330c5f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6ab6cab elementor-hidden-mobile\" data-id=\"6ab6cab\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffa5d5c elementor-widget elementor-widget-heading\" data-id=\"ffa5d5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00cdndice<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a359a bdt-content-position--left elementor-widget elementor-widget-bdt-fancy-list\" data-id=\"c1a359a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-fancy-list.default\">\n\t\t\t\t\t\t\t<div class=\"bdt-fancy-list bdt-fancy-list-style-1\">\n\t\t\t<ul class=\"bdt-list bdt-fancy-list-group\" class=\"bdt-fancy-list-icon\">\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-1\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tLa Indemnizaci\u00f3n Por Accidente Laboral es Un Seguro Sin Culpa\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-2\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tComo Pueden Suceder Las Lesiones Laborales\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-3\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tLeyes de Indemnizaci\u00f3n Laboral de California\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-4\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\t\u00bfQu\u00e9 Debes Hacer Si Te Lesionas en El Trabajo?\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-5\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\t\u00bfCu\u00e1les Son Mis Derechos Tras Sufrir Una Lesi\u00f3n Laboral en California?\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-7\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tTipos de Prestaciones Por Accidentes de Trabajo Disponibles en California\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-6\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tPrestaciones Por Accidentes de Trabajo en California\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-8\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\t\u00bfCu\u00e1nto Dura la Indemnizaci\u00f3n Por Accidente Laboral en California?\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-9\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\t\u00bfImporta la Culpa en Los Casos de Compensaci\u00f3n Laboral en California?\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-10\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\t\u00bfCu\u00e1les Son Las Lesiones Laborales M\u00e1s Comunes?\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-11\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\t\u00bfC\u00f3mo Ayuda Un Abogado Especializado en Lesiones Laborales Con Las Prestaciones?\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-12\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\t\u00bfCu\u00e1nto Cobra Un Abogado de Indemnizaci\u00f3n Por Accidente Laboral en California?\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-13\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tAcudir Al M\u00e9dico Por Primera Vez Tras Un Accidente Laboral\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-14\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tPonte en Contacto Con Un Abogado Laboralista Si Tu Empresa No Quiere O No Puede Ayudarte\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-15\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tMantener Tu Empleo Tras Presentar Una Demanda Por Accidente Laboral\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-16\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tResponsabilidad de terceros en lesiones laborales en California\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t<a class=\"bdt-fancy-list-wrap\" href=\"#a-17\">\t\t\t\t\t\t<div class=\"bdt-flex flex-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-fancy-list-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"bdt-fancy-list-title\">\n\t\t\t\t\t\t\t\t\t\t\tC\u00f3mo Pueden Ayudar Nuestros Experimentados Abogados de Indemnizaci\u00f3n Laboral de California\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7a53094 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a53094\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-85434c0\" data-id=\"85434c0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df801c5 elementor-widget elementor-widget-menu-anchor\" data-id=\"df801c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-6\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e07b4b elementor-widget elementor-widget-heading\" data-id=\"5e07b4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prestaciones Por Accidentes de Trabajo en California<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41fcb5e elementor-widget elementor-widget-text-editor\" data-id=\"41fcb5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p id=\"54eb9da0-05f1-4b6b-a368-4c80e70866ec\" class=\"quill-block\">En California, los trabajadores que se lesionan en el trabajo tienen derecho a recibir dos tercios de su salario bruto antes de impuestos, seg\u00fan dicta la ley estatal. Tambi\u00e9n hay una cantidad m\u00e1xima permitida.<\/p><p><strong>Estos Beneficios pueden desglosarse en los siguientes:<\/strong><\/p><p class=\"\"><strong>Incapacidad temporal<\/strong> &#8211; Los pagos por incapacidad temporal son redes de seguridad para los trabajadores lesionados. Si te lesionas en el trabajo y no puedes trabajar, puedes tener derecho a una prestaci\u00f3n por incapacidad temporal. Estos pagos suelen ser 2\/3 de tus ingresos brutos y est\u00e1n exentos de impuestos. Los ingresos brutos incluyen los ingresos antes de impuestos, como salarios, propinas, comisiones, primas y horas extraordinarias. La cuant\u00eda concreta de la incapacidad temporal depende de las circunstancias individuales de cada caso.<\/p><p class=\"\"><strong>Incapacidad permanente<\/strong> &#8211; Las indemnizaciones por incapacidad permanente se conceden a los trabajadores lesionados que son permanentemente incapaces de realizar su trabajo o actividades anteriores. Estos pagos se conceden aparte de la incapacidad temporal y el tratamiento m\u00e9dico, y la cuant\u00eda concedida var\u00eda en funci\u00f3n de cada caso.<\/p><p class=\"\">Los m\u00e9dicos asignan un n\u00famero de incapacidad basado en su informe m\u00e9dico para determinar las prestaciones por incapacidad permanente. El prorrateo determina el papel del accidente de trabajo en la incapacidad si \u00e9sta fue causada por algo distinto del accidente de trabajo.<\/p><p><strong>Tratamiento m\u00e9dico &#8211; <\/strong>En California, los trabajadores lesionados tienen derecho al tratamiento m\u00e9dico necesario para las lesiones sufridas en el trabajo, que deben proporcionar los empleador su seguro de accidentes de trabajo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-310c37c elementor-widget elementor-widget-image\" data-id=\"310c37c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/worker.jpg\" class=\"attachment-large size-large wp-image-46550\" alt=\"Prestaciones Por Accidentes de Trabajo en California\" srcset=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/worker.jpg 960w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/worker-300x200.jpg 300w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/worker-768x512.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7abaf32 elementor-widget elementor-widget-menu-anchor\" data-id=\"7abaf32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-7\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65e9794 elementor-widget elementor-widget-heading\" data-id=\"65e9794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tipos de Prestaciones Por Accidentes de Trabajo Disponibles en California<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b35bc elementor-widget elementor-widget-text-editor\" data-id=\"e1b35bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3>Tratamiento M\u00e9dico<\/h3><p>En California, los trabajadores lesionados tienen derecho al tratamiento m\u00e9dico necesario para curar y aliviar los efectos de las lesiones causadas por accidentes de trabajo. La ley obliga a los empleadores o a las aseguradoras de accidentes de trabajo de los empleadores a proporcionar cualquier tratamiento razonable por las lesiones sufridas en el trabajo.<\/p><h3>Asistencia M\u00e9dica de por Vida<\/h3><p class=\"\">El tratamiento m\u00e9dico de los accidentes de trabajo puede prolongarse durante largos periodos de tiempo, y no es responsabilidad tuya cubrir ning\u00fan coste asociado a tu accidente de trabajo durante el tratamiento. Si necesitas tratamiento m\u00e9dico para el resto de tu vida, la aseguradora de accidentes de trabajo debe hacerse cargo de cubrir los gastos mientras dure tu atenci\u00f3n m\u00e9dica.<\/p><h3>Bono Complementario de Desplazamiento Laboral<\/h3><p class=\"\">Si una persona no se ha reincorporado al trabajo tras recibir el visto bueno de su m\u00e9dico, puede optar a un vale que se entregar\u00e1 a una escuela. El importe del vale se determinar\u00e1 en funci\u00f3n de la discapacidad de la persona, y suele oscilar entre $6.000 o m\u00e1s o menos, seg\u00fan la fecha de la lesi\u00f3n.<\/p><h3>Prestaciones por Fallecimiento de Dependientes<\/h3><p class=\"\">La indemnizaci\u00f3n por accidente de trabajo proporciona prestaciones a los familiares a cargo que re\u00fanan los requisitos y cubre los gastos de entierro en caso de lesi\u00f3n o afecci\u00f3n m\u00e9dica relacionada con el trabajo que provoque la muerte del trabajador. La prestaci\u00f3n m\u00e1xima por familiares a cargo es de $320,000, y los gastos de sepelio est\u00e1n cubiertos hasta $10,000.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7adc094 elementor-widget elementor-widget-image\" data-id=\"7adc094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"538\" src=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-wrongful-death.jpg\" class=\"attachment-large size-large wp-image-46558\" alt=\"Tipos de Prestaciones Por Accidentes de Trabajo Disponibles en California\" srcset=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-wrongful-death.jpg 960w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-wrongful-death-300x168.jpg 300w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-wrongful-death-768x430.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4274de elementor-widget elementor-widget-menu-anchor\" data-id=\"a4274de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-8\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91c5ad2 elementor-widget elementor-widget-heading\" data-id=\"91c5ad2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1nto Dura la Indemnizaci\u00f3n Por Accidente Laboral en California?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7291c27 elementor-widget elementor-widget-text-editor\" data-id=\"7291c27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Las prestaciones por incapacidad temporal en California suelen <strong>finalizar al cabo de 104 semanas<\/strong>, aunque hay determinadas circunstancias en las que pueden hacerse excepciones, como en el caso de quemaduras graves o enfermedad pulmonar cr\u00f3nica, que podr\u00edan <strong>ampliar las prestaciones hasta 240 semanas<\/strong>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-481406e elementor-widget elementor-widget-text-editor\" data-id=\"481406e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>En Goldberg &amp; Loren, investigaremos a fondo su caso y reuniremos pruebas para construir un s\u00f3lido reclamo de indemnizaci\u00f3n. Lucharemos por obtener la m\u00e1xima indemnizaci\u00f3n posible en virtud de la Ley de lesiones personales de Oreg\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd1b4da elementor-widget elementor-widget-menu-anchor\" data-id=\"cd1b4da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-9\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-859a655 elementor-widget elementor-widget-heading\" data-id=\"859a655\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfImporta La Culpa en Los Casos de Compensaci\u00f3n Laboral en California?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd499b1 elementor-widget elementor-widget-text-editor\" data-id=\"dd499b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p id=\"54eb9da0-05f1-4b6b-a368-4c80e70866ec\" class=\"quill-block\">No, <strong>recibes prestaciones independientemente de qui\u00e9n haya tenido la culpa de tu lesi\u00f3n laboral<\/strong>. No puedes demandar a tu empleador por una lesi\u00f3n laboral (en la mayor\u00eda de los casos). Es ilegal que tu empleador te castigue o te despida por tener una lesi\u00f3n laboral o por solicitar prestaciones de compensaci\u00f3n a los trabajadores cuando crees que tu lesi\u00f3n fue causada por tu trabajo. [2]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-534c0ea elementor-widget elementor-widget-menu-anchor\" data-id=\"534c0ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-10\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6674941 elementor-widget elementor-widget-heading\" data-id=\"6674941\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1les Son Las Lesiones Laborales M\u00e1s Comunes?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e1b89d elementor-widget elementor-widget-text-editor\" data-id=\"5e1b89d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Algunas lesiones laborales son comunes a todos los sectores, como los resbalones y ca\u00eddas, las lesiones de espalda, las lesiones por movimientos repetitivos y el s\u00edndrome del t\u00fanel carpiano.<\/p>\n<p>Algunas de las lesiones laborales m\u00e1s comunes en California son:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3c39214 e-flex e-con-boxed e-con e-parent\" data-id=\"3c39214\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebfb4d0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ebfb4d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Amputaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lesiones de brazo, hombro, mu\u00f1eca o codo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lesiones de espalda<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Huesos rotos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Quemaduras<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Descargas el\u00e9ctricas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lesi\u00f3n ocular<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P\u00e9rdida auditiva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6639aa elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a6639aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Par\u00e1lisis<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Laceraci\u00f3n grave (corte)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Resbal\u00f3n y ca\u00edda<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lesi\u00f3n medular<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lesiones cerebrales traum\u00e1ticas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Latigazo cervical<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Muerte por negligencia<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Otras lesiones<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a73b9cf elementor-widget elementor-widget-image\" data-id=\"a73b9cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"538\" src=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-medical-conditions.jpg\" class=\"attachment-large size-large wp-image-46556\" alt=\"\u00bfCu\u00e1les Son Las Lesiones Laborales M\u00e1s Comunes?\" srcset=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-medical-conditions.jpg 960w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-medical-conditions-300x168.jpg 300w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2023\/11\/work-comp-medical-conditions-768x430.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a781669 elementor-widget elementor-widget-menu-anchor\" data-id=\"a781669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-11\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4812b8 elementor-widget elementor-widget-heading\" data-id=\"c4812b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo Ayuda Un Abogado Especializado en Lesiones Laborales Con Las Prestaciones?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e56fd0 elementor-widget elementor-widget-text-editor\" data-id=\"8e56fd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nuestros abogados especializados en lesiones laborales pueden ayudar a los trabajadores lesionados de California a comprender sus derechos y recibir las prestaciones que les corresponden.<\/p><p>Nuestros experimentados abogados de indemnizaci\u00f3n por accidente laboral de California investigar\u00e1n las circunstancias de la lesi\u00f3n, recopilar\u00e1n pruebas y luchar\u00e1n por conseguir un acuerdo justo para nuestros clientes.<\/p><p>Trabajaremos estrechamente con los proveedores m\u00e9dicos, los empleadores y las compa\u00f1\u00edas de seguros para asegurarnos de que el trabajador recibe todo el tratamiento m\u00e9dico necesario y las prestaciones compensatorias a las que tiene derecho seg\u00fan la ley.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52b3c54 elementor-widget elementor-widget-menu-anchor\" data-id=\"52b3c54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-12\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b031bb8 elementor-widget elementor-widget-heading\" data-id=\"b031bb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1nto Cobra Un Abogado de Indemnizaci\u00f3n Por Accidente Laboral en California?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5475389 elementor-widget elementor-widget-text-editor\" data-id=\"5475389\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Un abogado de indemnizaci\u00f3n por accidente laboral en California suele cobrar honorarios en funci\u00f3n <strong>de la contingencia<\/strong>, lo que significa que los honorarios del abogado se basan en un porcentaje del acuerdo o la indemnizaci\u00f3n.<\/p>\n<p>El juez de accidentes de trabajo autorizar\u00e1 los honorarios del abogado en funci\u00f3n de la cantidad de trabajo realizado y de lo que se haya recuperado para el cliente. Generalmente, los abogados se llevar\u00e1n un porcentaje de todas las prestaciones que se paguen a lo largo del tiempo del <strong>10%, el 12% o el 15%<\/strong>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c17c79 elementor-widget elementor-widget-menu-anchor\" data-id=\"8c17c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-13\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-924f914 elementor-widget elementor-widget-heading\" data-id=\"924f914\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acudir Al M\u00e9dico Por Primera Vez Tras Un Accidente Laboral<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfc21f3 elementor-widget elementor-widget-text-editor\" data-id=\"bfc21f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La primera vez que te re\u00fanes con un m\u00e9dico es muy importante. Es importante estar preparado para tu primera cita con el m\u00e9dico tras un accidente laboral. Aseg\u00farate de llevar todos los documentos e informaci\u00f3n pertinentes que puedan ayudar al m\u00e9dico a hacer un diagn\u00f3stico preciso, como un historial m\u00e9dico o historiales de lesiones o enfermedades relacionadas. Adem\u00e1s, debes tener una idea clara del tipo de tratamiento que el m\u00e9dico tiene previsto ofrecerte y de los plazos previstos.<\/p>\n<p>S\u00e9 sincero y abierto sobre los s\u00edntomas que experimentas y sobre cualquier informaci\u00f3n relevante que pueda ayudar al m\u00e9dico a hacer un diagn\u00f3stico preciso.<\/p>\n<p>Si tienes alguna pregunta o duda, no dudes en preguntarles. Las preguntas que habr\u00eda que hacer ser\u00edan<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-332aff8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"332aff8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfQu\u00e9 tratamientos ser\u00e1n necesarios para mi lesi\u00f3n o enfermedad?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfHabr\u00e1 efectos a largo plazo de esta lesi\u00f3n o enfermedad?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfCu\u00e1l es el plazo previsto para mi recuperaci\u00f3n?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfQu\u00e9 puedo hacer para acelerar el proceso de curaci\u00f3n?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfNecesitar\u00e9 atenci\u00f3n o visitas m\u00e9dicas adicionales en el futuro?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ca602d elementor-widget elementor-widget-menu-anchor\" data-id=\"1ca602d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-14\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de82dcc elementor-widget elementor-widget-heading\" data-id=\"de82dcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ponte en Contacto Con Un Abogado Laboralista Si Tu Empresa No Quiere O No Puede Ayudarte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec7892 elementor-widget elementor-widget-text-editor\" data-id=\"2ec7892\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Si tu supervisor o tu empleador no te ayudan a presentar una demanda de indemnizaci\u00f3n por accidente laboral ni te proporcionan prestaciones, es importante que te pongas en contacto lo antes posible con un abogado experto en indemnizaci\u00f3n por accidente laboral.<\/p><p>Un abogado experto en indemnizaci\u00f3n por accidente laboral en California puede ayudarte a garantizar que tus derechos est\u00e9n protegidos y que el proceso se desarrolle con fluidez y eficacia. Nuestros abogados tambi\u00e9n pueden asesorarte sobre c\u00f3mo recurrir una <a href=\"https:\/\/goldbergloren.com\/california-workers-comp-claims-denied\/\">recla un reclamo negado<\/a>\u00a0y a qu\u00e9 tipo de prestaciones puedes tener derecho.<\/p><p>Con d\u00e9cadas de experiencia, nuestros abogados conocen a fondo las complejas leyes y reglamentos que rigen los reclamos de indemnizaci\u00f3n de los trabajadores en California. Estamos preparados para luchar por ti y conseguir el mejor resultado posible para tu caso. Tambi\u00e9n puedes llamar al <strong><a href=\"tel:+18007367401\">1-800-736-7401<\/a> Centro de Servicios de Informaci\u00f3n DWC <\/strong>para hablar con un representante<strong>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad3218 elementor-widget elementor-widget-menu-anchor\" data-id=\"2ad3218\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-15\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acb0c56 elementor-widget elementor-widget-heading\" data-id=\"acb0c56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mantener Tu Empleo Tras Presentar Una Demanda Por Accidente Laboral<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3336724 elementor-widget elementor-widget-text-editor\" data-id=\"3336724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"\">En el estado de California, existe una ley que protege a los empleadores de represalias si presentan demandas de indemnizaci\u00f3n por accidente laboral. Esto significa que los empleadorios no pueden castigar a los empleados por presentar una reclamaci\u00f3n leg\u00edtima ni tratar de disuadirles de presentarla.<\/p><p class=\"\">El <a href=\"https:\/\/leginfo.legislature.ca.gov\/faces\/codes_displaySection.xhtml?lawCode=LAB&amp;sectionNum=132a.\" target=\"_blank\" rel=\"noopener\">art\u00edculo 132(a) del C\u00f3digo Laboral de California<\/a> proh\u00edbe \u00ab<strong><em>L<\/em><em>a <\/em><em>discriminaci\u00f3n de los trabajadores que sufren lesiones en el curso y el \u00e1mbito de su empleo<\/em><\/strong>\u00ab.<\/p><p class=\"\">Esto no significa que est\u00e9s absolutamente protegido, y tus acciones tras una reclamaci\u00f3n de indemnizaci\u00f3n laboral son igual de necesarias. La insubordinaci\u00f3n, ser grosero con los compa\u00f1eros o supervisores, o la falta de respeto pueden dar lugar a medidas disciplinarias.<\/p><p>Es importante que sigas actuando con profesionalidad y cumpliendo las normas de la empresa despu\u00e9s de presentar una demanda de indemnizaci\u00f3n por accidente laboral. Hacerlo puede ayudarte a protegerte de posibles represalias. Si crees que tu empleador est\u00e1 tomando represalias contra ti por presentar una demanda, ponte en contacto inmediatamente con un abogado experto en indemnizaci\u00f3n por accidente laboral.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2496ced elementor-widget elementor-widget-menu-anchor\" data-id=\"2496ced\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-16\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b702f43 elementor-widget elementor-widget-heading\" data-id=\"b702f43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Responsabilidad de Terceros en Lesiones Laborales en California<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed8c9c2 elementor-widget elementor-widget-text-editor\" data-id=\"ed8c9c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Cuando alguien se lesiona en el trabajo, el empleador puede ser considerado responsable de las lesiones sufridas. Sin embargo, hay casos en los que una parte externa o un tercero tambi\u00e9n pueden ser considerados responsables de lesiones sufridas en el trabajo. Este tipo de responsabilidad se conoce como responsabilidad frente a terceros.<\/p><p>En los casos de responsabilidad de terceros, el trabajador lesionado puede recibir una indemnizaci\u00f3n tanto del empleador como del tercero.<\/p><p>Algunos ejemplos habituales de responsabilidad civil son<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87c19cb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"87c19cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Negligencia de un contratista o subcontratista que trabaje por cuenta del empleador<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Un defecto del producto caus\u00f3 una lesi\u00f3n en el trabajo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accidente de tr\u00e1fico causado por un conductor no empleado por la empresa<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39dad8a elementor-widget elementor-widget-text-editor\" data-id=\"39dad8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Es importante que te pongas en contacto con un abogado experto en indemnizaci\u00f3n por accidente laboral para asegurarte de que recibes todas las prestaciones e indemnizaciones a las que tienes derecho. Un abogado puede ayudarte a investigar si un tercero es responsable de tus lesiones y, en caso afirmativo, emprender acciones legales contra \u00e9l.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcf40e5 elementor-widget elementor-widget-menu-anchor\" data-id=\"fcf40e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"a-17\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f50a37 elementor-widget elementor-widget-heading\" data-id=\"9f50a37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">C\u00f3mo Pueden Ayudar Nuestros Experimentados Abogados de Indemnizaci\u00f3n Laboral de California<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3264ba1 elementor-widget elementor-widget-text-editor\" data-id=\"3264ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Con m\u00e1s de 30 a\u00f1os de experiencia en derecho laboral, nuestros abogados especializados en indemnizaci\u00f3n por accidente de trabajo tienen los conocimientos y la experiencia necesarios para obtener los resultados que te mereces. Nos dedicamos a luchar por la justicia para los trabajadores lesionados de California.<\/p>\n<p>Nuestro experimentado equipo jur\u00eddico trabajar\u00e1 duro para conseguirte el tratamiento m\u00e9dico y la indemnizaci\u00f3n econ\u00f3mica que necesitas y mereces. Entendemos lo dif\u00edcil que puede ser para los trabajadores despu\u00e9s de una lesi\u00f3n, y estamos aqu\u00ed para ayudar. P\u00f3ngase en contacto con nosotros hoy mismo para una <a href=\"https:\/\/goldbergloren.com\/es\/contacte-con\/\">consulta gratuita<\/a>.<\/p>\n<p data-reactroot=\"\"><strong>Fuentes:<\/strong><\/p>\n<p data-reactroot=\"\">[1]<em> Principales causas de lesiones laborales &#8211; Hechos sobre lesiones<\/em>. (2023, 9 de enero). Datos sobre lesiones.  <a href=\"https:\/\/injuryfacts.nsc.org\/work\/work-overview\/top-work-related-injury-causes\/\" target=\"_blank\" rel=\"noopener\">https:\/\/injuryfacts.nsc.org\/work\/work-overview\/top-work-related-injury-causes\/<\/a><\/p>\n<p data-reactroot=\"\">[2] <a href=\"https:\/\/www.dir.ca.gov\/injuredworkerguidebook\/injuredworkerguidebook.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.dir.ca.gov\/injuredworkerguidebook\/injuredworkerguidebook.pdf<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-ce2afbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce2afbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-52a34fd\" data-id=\"52a34fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56420d9 bdt-ss-btns-style-framed bdt-ss-btns-view-icon-text bdt-ss-btns-shape-square bdt-ss-btns-color-original elementor-widget elementor-widget-bdt-social-share\" data-id=\"56420d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-social-share.default\">\n\t\t\t\t\t\t\t<div class=\"bdt-social-share bdt-ep-grid\">\n\t\t\t\t\t\t\t<div class=\"bdt-social-share-item bdt-ep-grid-item\">\n\t\t\t\t\t<div class=\"bdt-ss-btn bdt-ss-facebook\" data-social=\"facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ss-icon\">\n\t\t\t\t\t\t\t\t<i class=\"ep-icon-facebook\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-social-share-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-social-share-title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"bdt-social-share-item bdt-ep-grid-item\">\n\t\t\t\t\t<div class=\"bdt-ss-btn bdt-ss-linkedin\" data-social=\"linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ss-icon\">\n\t\t\t\t\t\t\t\t<i class=\"ep-icon-linkedin\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-social-share-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-social-share-title\">\n\t\t\t\t\t\t\t\t\t\tLinkedin\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"bdt-social-share-item bdt-ep-grid-item\">\n\t\t\t\t\t<div class=\"bdt-ss-btn bdt-ss-link\" data-social=\"link\" data-url=\"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/pages\/54192\/\" data-orginal=\"Copy Link\" data-copied=\"Copied\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-ss-icon\">\n\t\t\t\t\t\t\t\t<i class=\"ep-icon-link\"><\/i>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-social-share-text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-social-share-title\">\n\t\t\t\t\t\t\t\t\t\tCopy Link\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca30a99 elementor-widget elementor-widget-text-editor\" data-id=\"ca30a99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Goldberg &amp; Loren Abogados de Lesiones Personales<\/strong><\/p><p>2416 W Shaw Ave STE 114,<br \/>Fresno, CA 93711<\/p><p><a href=\"tel:+12132142826\">(213) 214-2826<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-72b4e1d\" data-id=\"72b4e1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-becf3c8 elementor-widget elementor-widget-html\" data-id=\"becf3c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script src=\"https:\/\/static.elfsight.com\/platform\/platform.js\" data-use-service-core=\"\" defer><\/script>\n<div class=\"elfsight-app-f3d1acdb-f639-44b1-b5b0-7e179185bd4d\" data-elfsight-app-lazy=\"\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcc2538 elementor-widget elementor-widget-google_maps\" data-id=\"fcc2538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Goldberg%20%26%20Loren%20Personal%20Injury%20Attorneys%20%202416%20W.%20Shaw%20Avenue.%20Suite%20103%20Fresno%2C%20CA%2093711&#038;t=m&#038;z=13&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Goldberg &amp; Loren Personal Injury Attorneys  2416 W. Shaw Avenue. Suite 103 Fresno, CA 93711\"\n\t\t\t\t\taria-label=\"Goldberg &amp; Loren Personal Injury Attorneys  2416 W. Shaw Avenue. Suite 103 Fresno, CA 93711\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8a24e60 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"8a24e60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-94ef7eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94ef7eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b720555\" data-id=\"b720555\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce2773d elementor-absolute elementor-widget elementor-widget-image\" data-id=\"ce2773d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"601\" src=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2022\/09\/loren.jpg\" class=\"attachment-full size-full wp-image-27961\" alt=\"James Loren\" srcset=\"https:\/\/goldbergloren.com\/wp-content\/uploads\/2022\/09\/loren.jpg 400w, https:\/\/goldbergloren.com\/wp-content\/uploads\/2022\/09\/loren-200x300.jpg 200w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-f5cd711 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5cd711\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8622917\" data-id=\"8622917\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a4fc3d elementor-blockquote--skin-quotation elementor-widget elementor-widget-blockquote\" data-id=\"9a4fc3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tSi te has lesionado en el trabajo, podemos ayudarte a obtener la indemnizaci\u00f3n que mereces. Ponte en contacto con nosotros.\t\t\t<\/p>\n\t\t\t\t\t\t\t<div class=\"e-q-footer\">\n\t\t\t\t\t\t\t\t\t\t\t<cite class=\"elementor-blockquote__author\">James Loren <br> Senior Partner<\/cite>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6bfb9ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bfb9ee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6943713\" data-id=\"6943713\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c14f01 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0c14f01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f9386d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0f9386d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11516e2 pp-dual-heading-inline elementor-widget elementor-widget-pp-dual-heading\" data-id=\"11516e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-dual-heading.default\">\n\t\t\t\t\t<h3 class=\"pp-dual-heading\"><span class=\"pp-first-text\">\u00bfNecesita ayuda? <\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a800436 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a800436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+12132142826\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(213) 214-2826<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d222f6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d222f6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fb5120 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7fb5120\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1f5bb6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f5bb6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-768101a\" data-id=\"768101a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-41f4de5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41f4de5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7b86f69\" data-id=\"7b86f69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9a53fa elementor-widget elementor-widget-google_maps\" data-id=\"e9a53fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=California&#038;t=m&#038;z=5&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"California\"\n\t\t\t\t\taria-label=\"California\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ea79a1 elementor-widget elementor-widget-heading\" data-id=\"9ea79a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Representamos a Empleados Lesionados en El Lugar de Trabajo en Toda California, Incluidas Las Siguientes Ciudades Y Comunidades:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-3fabfc2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3fabfc2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0179848\" data-id=\"0179848\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00f3887 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"00f3887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Los Angeles, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">San Diego, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">San Jos\u00e9, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">San Francisco, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fresno, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d58e43a\" data-id=\"d58e43a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af559ef elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"af559ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sacramento, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Long Beach, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Oakland, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bakersfield, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Anaheim, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cf68a56\" data-id=\"cf68a56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfc6c95 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"cfc6c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Stockton, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Riverside, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Irvine, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Santa Ana, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chula Vista, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-79ea26f\" data-id=\"79ea26f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07f2d16 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"07f2d16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fremont, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Santa Clarita, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">San Bernardino, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Modesto, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fontana, CA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9b614eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b614eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79f8ec8\" data-id=\"79f8ec8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c12a6a4 elementor-widget elementor-widget-heading\" data-id=\"c12a6a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00bfTiene preguntas sobre su caso? Ll\u00e1menos hoy mismo:<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bc0a300\" data-id=\"bc0a300\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7b80d3 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e7b80d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+12132142826\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(213) 214-2826<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Abogados con experiencia en Indemnizaci\u00f3n Laboral de California en una sola llamada Abogados de indemnizaci\u00f3n por accidente laboral en California Somos uno de los mejores bufetes de abogados de compensaci\u00f3n laboral de California. Obtenga una consulta gratuita Home La Indemnizaci\u00f3n Por Accidente Laboral es Un Seguro Sin Culpa La indemnizaci\u00f3n por accidente laboral es un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":46563,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-54192","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/pages\/54192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/comments?post=54192"}],"version-history":[{"count":0,"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/pages\/54192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/media\/46563"}],"wp:attachment":[{"href":"https:\/\/goldbergloren.com\/es\/wp-json\/wp\/v2\/media?parent=54192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}